{"id":2142,"date":"2022-08-16T15:45:19","date_gmt":"2022-08-16T15:45:19","guid":{"rendered":"https:\/\/www.stamm.bio\/?p=2142"},"modified":"2022-08-16T19:57:55","modified_gmt":"2022-08-16T19:57:55","slug":"bioprocesos-que-papel-juegan-las-celulas-en-esto","status":"publish","type":"post","link":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/","title":{"rendered":"Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por: Carolina C\u00e1rdenas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hablemos primero de lo tangible, del d\u00eda a d\u00eda. \u00bfD\u00f3nde se encuentran los bioprocesos? Por muy t\u00e9cnico y alejado que parezca, la producci\u00f3n basada en organismos biol\u00f3gicos es parte de nuestra vida diaria.&nbsp; La cerveza o copa de vino que compartes el fin de semana con amigos, as\u00ed como la producci\u00f3n de vacunas y medicamentos de base biol\u00f3gica son productos dados a trav\u00e9s de bioprocesos. Sin embargo, van m\u00e1s all\u00e1, estos nos permiten producciones industriales sostenibles que mitiguen la contaminaci\u00f3n ambiental y juegan un papel clave en la producci\u00f3n agr\u00edcola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El desarrollo de los bioprocesos a escala industrial parte del conocimiento que hemos obtenido sobre la din\u00e1mica celular presente en los organismos vivos. Es decir, \u00bfc\u00f3mo funcionan las c\u00e9lulas dentro de nosotros? Estas toman nutrientes de su medio para alimentarse, metabolizan un sustrato y dan como resultado un producto espec\u00edfico, permitiendo el correcto funcionamiento del organismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los bioprocesos son tan antiguos como las civilizaciones humanas. En el pasado, a trav\u00e9s de la observaci\u00f3n descubrimos cambios notorios producidos por los bioprocesos. Por ejemplo, en la fermentaci\u00f3n, la modificaci\u00f3n de lo sensorial de los alimentos y bebidas, as\u00ed como la concentraci\u00f3n alcoh\u00f3lica. Sin embargo, hasta ese entonces no ten\u00edamos un conocimiento exacto de qu\u00e9 era lo que suced\u00eda. Hoy en d\u00eda, con los avances de la ciencia y la tecnolog\u00eda hemos podido dilucidar los procesos mediante los cuales ocurre y usar la potencialidad natural de las c\u00e9lulas para producir a escala industrial un producto o servicio. Por otro lado, disciplinas como la microbiolog\u00eda, biolog\u00eda molecular, ingenier\u00eda, bioqu\u00edmica, entre otras, convergen en el desarrollo de los bioprocesos. Afortunadamente, hoy en d\u00eda la oferta de especialistas en estos campos es cada vez mayor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existen distintos tipos de c\u00e9lulas, y por consiguiente sus productos tambi\u00e9n lo son. Por mencionar algunos ejemplos: la producci\u00f3n de anticuerpos monoclonales ser\u00e1 a partir de c\u00e9lulas de mam\u00edferos, la penicilina a partir del hongo <em>penicillium<\/em>, enzimas utilizadas para biorremediaci\u00f3n de aguas residuales a partir de bacterias, mientras que, la producci\u00f3n de alcoholes fermentados ser\u00e1n a partir de levaduras.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las c\u00e9lulas utilizadas en la producci\u00f3n industrial necesitan crecer en un medio favorable. Se busca asemejar las condiciones de su entorno natural, es decir, ajustando el pH, la temperatura, la presi\u00f3n, la concentraci\u00f3n de O2 y CO2 y el suministro de nutrientes como carbono, nitr\u00f3geno, f\u00f3sforo o hidr\u00f3geno para convertirlos en un bioproducto.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la actualidad el m\u00e9todo est\u00e1ndar para realizar bioprocesos es mediante el uso de biorreactores. Estos son recipientes, especialmente tanques con agitaci\u00f3n que cuentan con condiciones ambientales controladas propicias para el crecimiento de las c\u00e9lulas y su consecuente producci\u00f3n de metabolitos de inter\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, desde nuestro punto de vista, este m\u00e9todo resulta ineficiente y poco accesible para las demandas de producci\u00f3n que tiene la humanidad hoy en d\u00eda. Por ejemplo, la incorporaci\u00f3n de ox\u00edgeno a trav\u00e9s de movimientos turbulentos pueden no ser los m\u00e1s \u201camigable\u201d para las c\u00e9lulas. Adem\u00e1s, tenemos escaso conocimiento de lo que sucede dentro de los biorreactores. Proponemos un sistema en el que la producci\u00f3n sea cont\u00ednua dentro de una estructura de espacio reducido suponiendo algo mucho m\u00e1s accesible en cuanto a costos e instalaci\u00f3n. De esta forma buscamos la democratizaci\u00f3n de los bioprocesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Permanece atento que a\u00fan tenemos mucha informaci\u00f3n para contarte!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Carolina C\u00e1rdenas Hablemos primero de lo tangible, del d\u00eda a d\u00eda. \u00bfD\u00f3nde se encuentran los bioprocesos? Por muy t\u00e9cnico y alejado que parezca, la producci\u00f3n basada en organismos biol\u00f3gicos es parte de nuestra vida diaria.&nbsp; La cerveza o copa de vino que compartes el fin de semana con amigos, as\u00ed como la producci\u00f3n de <a href=\"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/\" class=\"more-link\">&#8230;<span class=\"screen-reader-text\">  Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas?<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[36],"tags":[],"class_list":["post-2142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas? - St&auml;mm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas? - St&auml;mm\" \/>\n<meta property=\"og:description\" content=\"Por: Carolina C\u00e1rdenas Hablemos primero de lo tangible, del d\u00eda a d\u00eda. \u00bfD\u00f3nde se encuentran los bioprocesos? Por muy t\u00e9cnico y alejado que parezca, la producci\u00f3n basada en organismos biol\u00f3gicos es parte de nuestra vida diaria.&nbsp; La cerveza o copa de vino que compartes el fin de semana con amigos, as\u00ed como la producci\u00f3n de ... Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/\" \/>\n<meta property=\"og:site_name\" content=\"St&auml;mm\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-16T15:45:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-16T19:57:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stamm.bio\/wp-content\/uploads\/2022\/08\/1608-Blog-Bioprocesos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martina Casas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@StammBio\" \/>\n<meta name=\"twitter:site\" content=\"@StammBio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martina Casas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/es\\\/bioprocesos-que-papel-juegan-las-celulas-en-esto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/es\\\/bioprocesos-que-papel-juegan-las-celulas-en-esto\\\/\"},\"author\":{\"name\":\"Martina Casas\",\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/#\\\/schema\\\/person\\\/641964a13a7dddb6f42816a2c990cc25\"},\"headline\":\"Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas?\",\"datePublished\":\"2022-08-16T15:45:19+00:00\",\"dateModified\":\"2022-08-16T19:57:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/es\\\/bioprocesos-que-papel-juegan-las-celulas-en-esto\\\/\"},\"wordCount\":622,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/es\\\/bioprocesos-que-papel-juegan-las-celulas-en-esto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stamm.bio\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/1608-Blog-Bioprocesos.jpg\",\"articleSection\":[\"Tecnolog\u00edas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.stamm.bio\\\/es\\\/bioprocesos-que-papel-juegan-las-celulas-en-esto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/es\\\/bioprocesos-que-papel-juegan-las-celulas-en-esto\\\/\",\"url\":\"https:\\\/\\\/www.stamm.bio\\\/es\\\/bioprocesos-que-papel-juegan-las-celulas-en-esto\\\/\",\"name\":\"Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas? - St&auml;mm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/es\\\/bioprocesos-que-papel-juegan-las-celulas-en-esto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/es\\\/bioprocesos-que-papel-juegan-las-celulas-en-esto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stamm.bio\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/1608-Blog-Bioprocesos.jpg\",\"datePublished\":\"2022-08-16T15:45:19+00:00\",\"dateModified\":\"2022-08-16T19:57:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/es\\\/bioprocesos-que-papel-juegan-las-celulas-en-esto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stamm.bio\\\/es\\\/bioprocesos-que-papel-juegan-las-celulas-en-esto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/es\\\/bioprocesos-que-papel-juegan-las-celulas-en-esto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.stamm.bio\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/1608-Blog-Bioprocesos.jpg\",\"contentUrl\":\"https:\\\/\\\/www.stamm.bio\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/1608-Blog-Bioprocesos.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/es\\\/bioprocesos-que-papel-juegan-las-celulas-en-esto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.stamm.bio\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/#website\",\"url\":\"https:\\\/\\\/www.stamm.bio\\\/\",\"name\":\"St\u00e4mm\",\"description\":\"Internet of life\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stamm.bio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/#organization\",\"name\":\"St\u00e4mm\",\"url\":\"https:\\\/\\\/www.stamm.bio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stamm.bio\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/st_logo_green.png\",\"contentUrl\":\"https:\\\/\\\/www.stamm.bio\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/st_logo_green.png\",\"width\":310,\"height\":60,\"caption\":\"St\u00e4mm\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/StammBio\",\"https:\\\/\\\/www.instagram.com\\\/stamm.bio\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/stammbiotech\\\/\",\"https:\\\/\\\/medium.com\\\/@StammBio\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.stamm.bio\\\/#\\\/schema\\\/person\\\/641964a13a7dddb6f42816a2c990cc25\",\"name\":\"Martina Casas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9724dbbc54378a0c7d817ee456253f53208449497f615e08f5938cee4564c7ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9724dbbc54378a0c7d817ee456253f53208449497f615e08f5938cee4564c7ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9724dbbc54378a0c7d817ee456253f53208449497f615e08f5938cee4564c7ed?s=96&d=mm&r=g\",\"caption\":\"Martina Casas\"},\"url\":\"https:\\\/\\\/www.stamm.bio\\\/es\\\/author\\\/martina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas? - St&auml;mm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/","og_locale":"es_ES","og_type":"article","og_title":"Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas? - St&auml;mm","og_description":"Por: Carolina C\u00e1rdenas Hablemos primero de lo tangible, del d\u00eda a d\u00eda. \u00bfD\u00f3nde se encuentran los bioprocesos? Por muy t\u00e9cnico y alejado que parezca, la producci\u00f3n basada en organismos biol\u00f3gicos es parte de nuestra vida diaria.&nbsp; La cerveza o copa de vino que compartes el fin de semana con amigos, as\u00ed como la producci\u00f3n de ... Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas?","og_url":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/","og_site_name":"St&auml;mm","article_published_time":"2022-08-16T15:45:19+00:00","article_modified_time":"2022-08-16T19:57:55+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.stamm.bio\/wp-content\/uploads\/2022\/08\/1608-Blog-Bioprocesos.jpg","type":"image\/jpeg"}],"author":"Martina Casas","twitter_card":"summary_large_image","twitter_creator":"@StammBio","twitter_site":"@StammBio","twitter_misc":{"Escrito por":"Martina Casas","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/#article","isPartOf":{"@id":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/"},"author":{"name":"Martina Casas","@id":"https:\/\/www.stamm.bio\/#\/schema\/person\/641964a13a7dddb6f42816a2c990cc25"},"headline":"Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas?","datePublished":"2022-08-16T15:45:19+00:00","dateModified":"2022-08-16T19:57:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/"},"wordCount":622,"commentCount":0,"publisher":{"@id":"https:\/\/www.stamm.bio\/#organization"},"image":{"@id":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stamm.bio\/wp-content\/uploads\/2022\/08\/1608-Blog-Bioprocesos.jpg","articleSection":["Tecnolog\u00edas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/","url":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/","name":"Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas? - St&auml;mm","isPartOf":{"@id":"https:\/\/www.stamm.bio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/#primaryimage"},"image":{"@id":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stamm.bio\/wp-content\/uploads\/2022\/08\/1608-Blog-Bioprocesos.jpg","datePublished":"2022-08-16T15:45:19+00:00","dateModified":"2022-08-16T19:57:55+00:00","breadcrumb":{"@id":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/#primaryimage","url":"https:\/\/www.stamm.bio\/wp-content\/uploads\/2022\/08\/1608-Blog-Bioprocesos.jpg","contentUrl":"https:\/\/www.stamm.bio\/wp-content\/uploads\/2022\/08\/1608-Blog-Bioprocesos.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.stamm.bio\/es\/bioprocesos-que-papel-juegan-las-celulas-en-esto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stamm.bio\/es\/"},{"@type":"ListItem","position":2,"name":"Bioprocesos \u00bfQu\u00e9 papel juegan las c\u00e9lulas?"}]},{"@type":"WebSite","@id":"https:\/\/www.stamm.bio\/#website","url":"https:\/\/www.stamm.bio\/","name":"St\u00e4mm","description":"Internet of life","publisher":{"@id":"https:\/\/www.stamm.bio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stamm.bio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.stamm.bio\/#organization","name":"St\u00e4mm","url":"https:\/\/www.stamm.bio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.stamm.bio\/#\/schema\/logo\/image\/","url":"https:\/\/www.stamm.bio\/wp-content\/uploads\/2025\/02\/st_logo_green.png","contentUrl":"https:\/\/www.stamm.bio\/wp-content\/uploads\/2025\/02\/st_logo_green.png","width":310,"height":60,"caption":"St\u00e4mm"},"image":{"@id":"https:\/\/www.stamm.bio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/StammBio","https:\/\/www.instagram.com\/stamm.bio\/","https:\/\/www.linkedin.com\/company\/stammbiotech\/","https:\/\/medium.com\/@StammBio"]},{"@type":"Person","@id":"https:\/\/www.stamm.bio\/#\/schema\/person\/641964a13a7dddb6f42816a2c990cc25","name":"Martina Casas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9724dbbc54378a0c7d817ee456253f53208449497f615e08f5938cee4564c7ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9724dbbc54378a0c7d817ee456253f53208449497f615e08f5938cee4564c7ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9724dbbc54378a0c7d817ee456253f53208449497f615e08f5938cee4564c7ed?s=96&d=mm&r=g","caption":"Martina Casas"},"url":"https:\/\/www.stamm.bio\/es\/author\/martina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.stamm.bio\/es\/wp-json\/wp\/v2\/posts\/2142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stamm.bio\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stamm.bio\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stamm.bio\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stamm.bio\/es\/wp-json\/wp\/v2\/comments?post=2142"}],"version-history":[{"count":3,"href":"https:\/\/www.stamm.bio\/es\/wp-json\/wp\/v2\/posts\/2142\/revisions"}],"predecessor-version":[{"id":2152,"href":"https:\/\/www.stamm.bio\/es\/wp-json\/wp\/v2\/posts\/2142\/revisions\/2152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stamm.bio\/es\/wp-json\/wp\/v2\/media\/2145"}],"wp:attachment":[{"href":"https:\/\/www.stamm.bio\/es\/wp-json\/wp\/v2\/media?parent=2142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stamm.bio\/es\/wp-json\/wp\/v2\/categories?post=2142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stamm.bio\/es\/wp-json\/wp\/v2\/tags?post=2142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}